{"id":14809,"date":"2024-06-25T15:58:31","date_gmt":"2024-06-25T15:58:31","guid":{"rendered":"https:\/\/good-search.org\/about\/?p=14809"},"modified":"2024-07-05T07:21:34","modified_gmt":"2024-07-05T07:21:34","slug":"aufforstung-von-regenwald-so-gross-wie-fussballfelder","status":"publish","type":"post","link":"https:\/\/good-search.org\/about\/blog\/aufforstung-von-regenwald-so-gross-wie-fussballfelder\/","title":{"rendered":"Kampagne zur UEFA EURO 2024: Aufforstung von Regenwald so gro\u00df wie Fu\u00dfballfelder"},"content":{"rendered":"<style type=\"text\/css\"> \n#cmsmasters_row_6a570d0d2a4c63_28135667 .cmsmasters_row_outer_parent { \n\tpadding-top: 20px; \n} \n\n#cmsmasters_row_6a570d0d2a4c63_28135667 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 15px; \n} \n\n \n#cmsmasters_row_6a570d0d2a7235_19723979 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a570d0d2a7235_19723979 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 10px; \n} \n\n<\/style><div id=\"cmsmasters_row_6a570d0d2a4c63_28135667\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_text\">\n<p>&nbsp;<\/p>\n<div style=\"width: 848px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-14809-1\" width=\"848\" height=\"480\" poster=\"https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/Generation_Forest_EM_Kampagne.png\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/EM-Film-TGF-Small.mp4?_=1\" \/><a href=\"https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/EM-Film-TGF-Small.mp4\">https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/EM-Film-TGF-Small.mp4<\/a><\/video><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a570d0d2a7235_19723979\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_text\">\n<h3><strong>Wir kennen das Generation Forest-Projekt vor Ort in Panama. Ein guter Grund, die aktuelle Kampagne zur EURO 2024 zu unterst\u00fctzen!<\/strong><\/h3>\n<p>Fu\u00dfball ist f\u00fcr viele Menschen die tollste Sache der Welt. Eigentlich schade, dass sich Fu\u00dfballfelder als Bezugsgr\u00f6\u00dfe etabliert haben, wenn es um die Messung der Zerst\u00f6rung von Regenw\u00e4ldern geht. Nach Sch\u00e4tzung von <a href=\"https:\/\/www.nationalgeographic.de\/umwelt\/2022\/02\/gerodet-fuer-eu-konsum-fast-1000-fussballfelder-waldflaeche-taeglich\">National Geographic<\/a> verursacht unser Konsum von Palm\u00f6l, Kaffee und Fleisch einen Verlust in einer Gr\u00f6\u00dfenordnung von 1000 Fu\u00dfballfeldern t\u00e4glich.<\/p>\n<p>Diesen Konflikt m\u00f6chte die noch\u00a0<span style=\"font-weight: 400\">junge Stiftung Generation Forest aus Hamburg ein St\u00fcck weit aufl\u00f6sen. Passend zur Fu\u00dfball-Europameisterschaft in Deutschland hat sie eine <a href=\"https:\/\/em-regenwald.generationforestfoundation.com\">Spendenkampagne<\/a> gestartet, bei der jeder Fu\u00dfball-Fan auf spielerische Weise ein St\u00fcck Regenwald zur\u00fcckholen kann \u2013 in Gr\u00f6\u00dfe des Mittelkreises, des Strafraums oder gleich eines halben Spielfeldes. Fl\u00e4chen, die dann in Zentralamerika neu aufgeforstet werden.<\/span><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<p>Das Modell l\u00e4dt zu Kreativit\u00e4t ein. Warum nicht im Freundeskreis ein esoziales EM-Tippspiel starten und die Wetteins\u00e4tze der Generation Forest Stiftung spenden? Die M\u00f6glichkeiten sind so bunt wie die Meisterschaft selbst.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14812\" src=\"https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/Stadion_Still_sRGB-1024x658.jpg\" alt=\"\" width=\"1024\" height=\"658\" srcset=\"https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/Stadion_Still_sRGB-1024x658.jpg 1024w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/Stadion_Still_sRGB-300x193.jpg 300w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/Stadion_Still_sRGB-768x494.jpg 768w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/Stadion_Still_sRGB-1536x988.jpg 1536w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/Stadion_Still_sRGB-2048x1317.jpg 2048w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/Stadion_Still_sRGB-580x373.jpg 580w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/Stadion_Still_sRGB-860x553.jpg 860w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/Stadion_Still_sRGB-1160x746.jpg 1160w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2024\/06\/Stadion_Still_sRGB-1440x926.jpg 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h3><strong>Spende oder Investment? \u2013 Beides.\u00a0<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">Die Aufforstung der Fl\u00e4chen erfolgt \u00fcber die gleichnamige Hamburger Genossenschaft, an der wir \u00fcber unsere gemeinn\u00fctzige Stiftung selbst auch beteiligt sind.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Das Konzept \u00fcberzeugt uns: Die Genossenschaft \u00fcbernimmt brachliegende Fl\u00e4chen in Panama, die nicht mehr bewohnt sind. Solche Fl\u00e4chen gibt es en masse. Denn viel Regenwald wurde abgeholzt, um Rinderzucht zu betreiben. Auf Dauer ist dies kein lukratives Gesch\u00e4ft. Denn in den Tropen laugen die B\u00f6den meist schnell aus und der Regen schwemmt die letzte Erde davon. Von alleine erholen sich diese Fl\u00e4chen nicht. Es bedarf daher einer aktiven Aufforstung oder \u2013 bei gestr\u00fcppartigen Sekund\u00e4rw\u00e4ldern \u2013 einer gezielten Anreicherung mit heimischen Baumarten, um abwechslungsreiche, nat\u00fcrliche \u00d6kosysteme zu schaffen, die Lebensr\u00e4ume f\u00fcr seltene Tiere und Pflanzen bieten. Die Setzlinge bezieht die Genossenschaft \u00fcber eine Partnerschaft mit einer indigenen Community, die in bestehenden W\u00e4ldern Saatgut sammelt und in einer neu geschaffenen Baumschule z\u00fcchtet.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Damit der Wald auch noch in 100 Jahren gepflegt und gesch\u00fctzt werden kann, sieht das Konzept vor, sp\u00e4ter einzelne B\u00e4ume zu f\u00e4llen und das Holz zu verkaufen, ohne jedoch dadurch das durchg\u00e4ngige Bl\u00e4tterdach zu verlieren. So entstehen Einnahmen, mit denen das Forst-Team vor Ort bezahlt, die W\u00e4lder vor Feuer oder illegalem Holzeinschlag gesch\u00fctzt und lokale Baumschulen vor Ort aufgebaut werden, um weitere W\u00e4lder zu pflanzen. Denn die Einnahmen, die an die Generation Forest Stiftung zur\u00fcckflie\u00dfen, sollen einmal dazu dienen, noch mehr Regenwald wiederherzustellen. So wird aus der Spende langfristig ein Investment in unseren Planeten.<\/span><\/p>\n<h3><strong>Regenwald dauerhaft sch\u00fctzen ohne Fu\u00dfball? Geht auch direkt \u00fcber die Genossenschaft<\/strong><\/h3>\n<p>An der Genossenschaft k\u00f6nnt ihr euch \u00fcbrigens auch direkt beteiligen, losgel\u00f6st von der Fu\u00dfball-EM. Mit mehr als 7000 Mitgliedern ist die <a href=\"https:\/\/thegenerationforest.com\">The Generation Forest e.G<\/a>. schon heute die gr\u00f6\u00dfte deutsche Waldgenossenschaft.<\/p>\n<p>Jeder Genossenschaftsanteil entspricht dabei etwa 500 Quadratmeter Wald, der etwa eine Tonne CO2 pro Jahr speichert, und zwar jedes Jahr erneut auf sehr lange Sicht. Ein Anteil kostet aktuell etwa 1.500 Euro. Der Preis erh\u00f6ht sich in der Regel um 4.5% pro Jahr. Dies entspricht dem gesch\u00e4tzten Wertzuwachs der B\u00e4ume. Die Spende zur EM hat vor allem den Vorteil, dass sie leicht und schnell umsetzbar ist, auch mit kleinen Betr\u00e4gen.<\/p>\n<figure id=\"attachment_6301\" aria-describedby=\"caption-attachment-6301\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-6301\" src=\"https:\/\/good-search.org\/about\/wp-content\/uploads\/2020\/10\/Brain-Forest_Darien_high-pruning_2015_4_1100-1024x640.jpg\" alt=\"\" width=\"1024\" height=\"640\" srcset=\"https:\/\/good-search.org\/about\/wp-content\/uploads\/2020\/10\/Brain-Forest_Darien_high-pruning_2015_4_1100-1024x640.jpg 1024w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2020\/10\/Brain-Forest_Darien_high-pruning_2015_4_1100-300x188.jpg 300w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2020\/10\/Brain-Forest_Darien_high-pruning_2015_4_1100-768x480.jpg 768w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2020\/10\/Brain-Forest_Darien_high-pruning_2015_4_1100-580x363.jpg 580w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2020\/10\/Brain-Forest_Darien_high-pruning_2015_4_1100-860x538.jpg 860w, https:\/\/good-search.org\/about\/wp-content\/uploads\/2020\/10\/Brain-Forest_Darien_high-pruning_2015_4_1100.jpg 1100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-6301\" class=\"wp-caption-text\">Bild: The Generation Forest<\/figcaption><\/figure>\n<h3><\/h3>\n<h3><strong>Gewusst? \u2013 Die UEFA unterst\u00fctz Klimaprojekte lokaler Fu\u00dfballvereine in Deutschland<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">Wie jedes Gro\u00dfevent verursacht die Fu\u00dfball EM 2024 erhebliche Mengen an CO2-Emissionen, fast eine halbe Millionen Tonnen nach einer Berechnung des Freiburger \u00d6ko-Instituts.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die UEFA versucht diese durch eigene Ma\u00dfnahmen zu reduzieren und hat unter dem Motto \u201eUnited by Football \u2013 Together for Nature\u201c einen mit ca 7 Millionen Euro gef\u00fcllten Fonds f\u00fcr Klimaschutzprojekte eingerichtet. Deutsche Amateurvereine k\u00f6nnen sich noch bis zum 30. Juni um F\u00f6rdermittel f\u00fcr eigene Klimaschutzprojekte wie die Installation von LED-Flutlichtern bewerben.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Mit der Kampagne der Generation Forest Stiftung profitieren dann auch Menschen im globalen S\u00fcden, die am meisten unter dem Klimawandel leiden. Und sie hinterl\u00e4sst einen bleibenden Eindruck: Denn die W\u00e4lder werden \u2013 so die Ambition \u2013 f\u00fcr die Ewigkeit gepflanzt.\u00a0<\/span><\/p>\n<p><strong>Fragen, Kritik, Anregungen? Schreibt uns!<br \/>\n<\/strong><span style=\"font-weight: 400\">Andreas Renner,\u00a0<\/span><span style=\"font-weight: 400\">Co-Founder GOOD:\u00a0<\/span><a href=\"mailto:andreas@good-search.org\"><span style=\"font-weight: 400\">andreas@good-search.org<\/span><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a570d0d2a9bf7_46065985\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_text\">\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Wir kennen das Generation Forest-Projekt vor Ort in Panama seit der ersten Stunde und lieben es. Ein guter Grund, die aktuelle Kampagne zur EM zu unterst\u00fctzen!<\/p>\n","protected":false},"author":3,"featured_media":14884,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34,74],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/good-search.org\/about\/wp-json\/wp\/v2\/posts\/14809"}],"collection":[{"href":"https:\/\/good-search.org\/about\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/good-search.org\/about\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/good-search.org\/about\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/good-search.org\/about\/wp-json\/wp\/v2\/comments?post=14809"}],"version-history":[{"count":30,"href":"https:\/\/good-search.org\/about\/wp-json\/wp\/v2\/posts\/14809\/revisions"}],"predecessor-version":[{"id":15031,"href":"https:\/\/good-search.org\/about\/wp-json\/wp\/v2\/posts\/14809\/revisions\/15031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/good-search.org\/about\/wp-json\/wp\/v2\/media\/14884"}],"wp:attachment":[{"href":"https:\/\/good-search.org\/about\/wp-json\/wp\/v2\/media?parent=14809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/good-search.org\/about\/wp-json\/wp\/v2\/categories?post=14809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/good-search.org\/about\/wp-json\/wp\/v2\/tags?post=14809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}